{"id":1365,"date":"2023-03-21T18:47:16","date_gmt":"2023-03-21T21:47:16","guid":{"rendered":"https:\/\/ifd1-nqn.infd.edu.ar\/sitio\/?p=1365"},"modified":"2023-03-21T18:47:18","modified_gmt":"2023-03-21T21:47:18","slug":"talleres-de-inicio","status":"publish","type":"post","link":"https:\/\/ifd1-nqn.infd.edu.ar\/sitio\/talleres-de-inicio\/","title":{"rendered":"Talleres de inicio"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" loading=\"lazy\" width=\"1080\" height=\"1080\" src=\"https:\/\/ifd1-nqn.infd.edu.ar\/sitio\/wp-content\/uploads\/2023\/03\/WhatsApp_Image_2023-03-20_at_21.15.17-1.jpg\" alt=\"\" class=\"wp-image-1366\" srcset=\"https:\/\/ifd1-nqn.infd.edu.ar\/sitio\/wp-content\/uploads\/2023\/03\/WhatsApp_Image_2023-03-20_at_21.15.17-1.jpg 1080w, https:\/\/ifd1-nqn.infd.edu.ar\/sitio\/wp-content\/uploads\/2023\/03\/WhatsApp_Image_2023-03-20_at_21.15.17-1-1000x1000.jpg 1000w, https:\/\/ifd1-nqn.infd.edu.ar\/sitio\/wp-content\/uploads\/2023\/03\/WhatsApp_Image_2023-03-20_at_21.15.17-1-500x500.jpg 500w, https:\/\/ifd1-nqn.infd.edu.ar\/sitio\/wp-content\/uploads\/2023\/03\/WhatsApp_Image_2023-03-20_at_21.15.17-1-768x768.jpg 768w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/figure>\n\n\n\n<p><strong>Hola a todxs!\u00a0<\/strong><\/p>\n\n\n\n<p>Compartimos las actividades institucionales para el taller de inicio.&nbsp;<\/p>\n\n\n\n<p><strong>Mi\u00e9rcoles 15.00 \u2013 17.00<\/strong><\/p>\n\n\n\n<ul>\n<li>Recepci\u00f3n de todxs lxs ingresantes en el S.U.M. \u2013 bienvenida institucional<\/li>\n\n\n\n<li>Recorrido colectivo de la muestra en el escenario<\/li>\n\n\n\n<li>Divisi\u00f3n de los 5 grupos de trabajo<\/li>\n<\/ul>\n\n\n\n<p><strong>1) \u201cA ventanas abiertas: pensando en la docencia\u201d<\/strong>&nbsp;(dos grupos en aula nueva y aula 1), a cargo de Carlos Fuentes, Yasna Leuze, Silvia Su\u00e1rez, Carina Fr\u00e9, Florencia Lasalle, Jonathan Pelliza, Luciana C\u00e1ceres y Yanet Dur\u00e1n<\/p>\n\n\n\n<p><strong>2) \u201cUn cuarto propio: la mujer y la literatura desde una perspectiva de g\u00e9nero\u201d<\/strong>&nbsp;(un grupo en aula 10), a cargo de Julieta Abarz\u00faa, Viviana Garrido, Paola N\u00fa\u00f1ez, Mariela Racedo y Silvana Antinao<\/p>\n\n\n\n<p><strong>3) \u201cMemoria, verdad y justicia como pr\u00e1ctica cotidiana en las instituciones educativas\u201d<\/strong>&nbsp;(un grupo en aula 8), a cargo de Denise Vargas, Nancy Figueroa, Carina Rodr\u00edguez, Belinda Figueroa y Lautaro Su\u00e1rez<\/p>\n\n\n\n<p><strong>4) \u201cCine debate: derechos humanos, educaci\u00f3n y diversidad\u201d<\/strong>&nbsp;(un grupo en Biblioteca), a cargo de Lucas Montecino, Ayel\u00e9n Pacheco y Daniela Silva<\/p>\n\n\n\n<p>Cada grupo de profes cierra la jornada en su taller<\/p>\n\n\n\n<p><strong>Jueves 15.00 \u2013 16.30<\/strong><\/p>\n\n\n\n<p>Talleres simult\u00e1neos a cargo de preceptores, bedeles, tutores y equipo directivo<\/p>\n\n\n\n<p><strong>\u201cLas trayectorias escolares en formaci\u00f3n docente\u201d&nbsp;<\/strong>(tres grupos en aula nueva, aula 1 y aula 10)<\/p>\n\n\n\n<p>Saludos a todxs!!!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hola a todxs!\u00a0 Compartimos las actividades institucionales para el taller de inicio.&nbsp; Mi\u00e9rcoles 15.00 \u2013 17.00 1) \u201cA ventanas abiertas: pensando en la docencia\u201d&nbsp;(dos grupos en aula nueva y aula 1), a cargo de Carlos Fuentes, Yasna Leuze, Silvia Su\u00e1rez, Carina Fr\u00e9, Florencia Lasalle, Jonathan Pelliza, Luciana C\u00e1ceres y Yanet Dur\u00e1n 2) \u201cUn cuarto propio: &#8230; <a title=\"Talleres de inicio\" class=\"read-more\" href=\"https:\/\/ifd1-nqn.infd.edu.ar\/sitio\/talleres-de-inicio\/\" aria-label=\"More on Talleres de inicio\">[+]<\/a><\/p>\n","protected":false},"author":688,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/ifd1-nqn.infd.edu.ar\/sitio\/wp-json\/wp\/v2\/posts\/1365"}],"collection":[{"href":"https:\/\/ifd1-nqn.infd.edu.ar\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ifd1-nqn.infd.edu.ar\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ifd1-nqn.infd.edu.ar\/sitio\/wp-json\/wp\/v2\/users\/688"}],"replies":[{"embeddable":true,"href":"https:\/\/ifd1-nqn.infd.edu.ar\/sitio\/wp-json\/wp\/v2\/comments?post=1365"}],"version-history":[{"count":1,"href":"https:\/\/ifd1-nqn.infd.edu.ar\/sitio\/wp-json\/wp\/v2\/posts\/1365\/revisions"}],"predecessor-version":[{"id":1367,"href":"https:\/\/ifd1-nqn.infd.edu.ar\/sitio\/wp-json\/wp\/v2\/posts\/1365\/revisions\/1367"}],"wp:attachment":[{"href":"https:\/\/ifd1-nqn.infd.edu.ar\/sitio\/wp-json\/wp\/v2\/media?parent=1365"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ifd1-nqn.infd.edu.ar\/sitio\/wp-json\/wp\/v2\/categories?post=1365"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ifd1-nqn.infd.edu.ar\/sitio\/wp-json\/wp\/v2\/tags?post=1365"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}